{"id":688,"count":35,"description":"","link":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/","name":"Lampes","slug":"lampen-salonapparatuur-2-fr","taxonomy":"product_cat","parent":817,"meta":[],"menu_order":148,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lampes - Bowie Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lampes - Bowie Medical\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Bowie Medical\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/categorie-produit\\\/equipement-de-salon-fr\\\/lampen-salonapparatuur-2-fr\\\/\",\"url\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/categorie-produit\\\/equipement-de-salon-fr\\\/lampen-salonapparatuur-2-fr\\\/\",\"name\":\"Lampes - Bowie Medical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/categorie-produit\\\/equipement-de-salon-fr\\\/lampen-salonapparatuur-2-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/categorie-produit\\\/equipement-de-salon-fr\\\/lampen-salonapparatuur-2-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9quipement de salon\",\"item\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/categorie-produit\\\/equipement-de-salon-fr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lampes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/\",\"name\":\"Bowie Medical\",\"description\":\"Groothandel voor esthetiek en voetverzorging\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/#organization\",\"name\":\"Bowie Medical\",\"url\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bowiemedical.be\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/LogoRGB-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.bowiemedical.be\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/LogoRGB-scaled.png\",\"width\":2560,\"height\":797,\"caption\":\"Bowie Medical\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bowiemedical.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampes - Bowie Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Lampes - Bowie Medical","og_url":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/","og_site_name":"Bowie Medical","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/","url":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/","name":"Lampes - Bowie Medical","isPartOf":{"@id":"https:\/\/www.bowiemedical.be\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/lampen-salonapparatuur-2-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bowiemedical.be\/fr\/"},{"@type":"ListItem","position":2,"name":"\u00c9quipement de salon","item":"https:\/\/www.bowiemedical.be\/fr\/categorie-produit\/equipement-de-salon-fr\/"},{"@type":"ListItem","position":3,"name":"Lampes"}]},{"@type":"WebSite","@id":"https:\/\/www.bowiemedical.be\/fr\/#website","url":"https:\/\/www.bowiemedical.be\/fr\/","name":"Bowie Medical","description":"Groothandel voor esthetiek en voetverzorging","publisher":{"@id":"https:\/\/www.bowiemedical.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bowiemedical.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.bowiemedical.be\/fr\/#organization","name":"Bowie Medical","url":"https:\/\/www.bowiemedical.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bowiemedical.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.bowiemedical.be\/wp-content\/uploads\/2025\/07\/LogoRGB-scaled.png","contentUrl":"https:\/\/www.bowiemedical.be\/wp-content\/uploads\/2025\/07\/LogoRGB-scaled.png","width":2560,"height":797,"caption":"Bowie Medical"},"image":{"@id":"https:\/\/www.bowiemedical.be\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.bowiemedical.be\/fr\/wp-json\/wp\/v2\/product_cat\/688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bowiemedical.be\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.bowiemedical.be\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.bowiemedical.be\/fr\/wp-json\/wp\/v2\/product_cat\/817"}],"wp:post_type":[{"href":"https:\/\/www.bowiemedical.be\/fr\/wp-json\/wp\/v2\/product?product_cat=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}